{"id":29,"count":3,"description":"","link":"https:\/\/pfadvisors.co.uk\/en\/kategoria\/equity-release\/","name":"Equity Release","slug":"equity-release","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Equity Release - Kategoria Blogowa - Prestige Financial Advisers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pfadvisors.co.uk\/en\/kategoria\/equity-release\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equity Release - Kategoria Blogowa - Prestige Financial Advisers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pfadvisors.co.uk\/en\/kategoria\/equity-release\/\" \/>\n<meta property=\"og:site_name\" content=\"Prestige Financial Advisers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Equity Release - Kategoria Blogowa - Prestige Financial Advisers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pfadvisors.co.uk\/en\/kategoria\/equity-release\/","og_locale":"en_US","og_type":"article","og_title":"Equity Release - Kategoria Blogowa - Prestige Financial Advisers","og_url":"https:\/\/pfadvisors.co.uk\/en\/kategoria\/equity-release\/","og_site_name":"Prestige Financial Advisers","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/pfadvisors.co.uk\/en\/kategoria\/equity-release\/","url":"https:\/\/pfadvisors.co.uk\/en\/kategoria\/equity-release\/","name":"Equity Release - Kategoria Blogowa - Prestige Financial Advisers","isPartOf":{"@id":"https:\/\/pfadvisors.co.uk\/en\/#website"},"breadcrumb":{"@id":"https:\/\/pfadvisors.co.uk\/en\/kategoria\/equity-release\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/pfadvisors.co.uk\/en\/kategoria\/equity-release\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pfadvisors.co.uk\/en\/"},{"@type":"ListItem","position":2,"name":"Equity Release"}]},{"@type":"WebSite","@id":"https:\/\/pfadvisors.co.uk\/en\/#website","url":"https:\/\/pfadvisors.co.uk\/en\/","name":"Prestige Financial Advisers","description":"Polska firma doradztwa ubezpieczeniowego w UK","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pfadvisors.co.uk\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/pfadvisors.co.uk\/en\/wp-json\/wp\/v2\/categories\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pfadvisors.co.uk\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/pfadvisors.co.uk\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/pfadvisors.co.uk\/en\/wp-json\/wp\/v2\/posts?categories=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}